{"id":277593,"date":"2025-07-03T16:58:55","date_gmt":"2025-07-03T16:58:55","guid":{"rendered":"https:\/\/www.bidc-ebid.org\/fr\/?p=277593"},"modified":"2025-07-03T16:58:55","modified_gmt":"2025-07-03T16:58:55","slug":"le-conseil-dadministration-de-la-bidc-approuve-un-investissement-de-174-millions-deuros-et-de-125-millions-de-dollars-us-pour-stimuler-le-commerce-renforcer-les-infrastructures-et-soutenir-le-dev","status":"publish","type":"post","link":"https:\/\/www.bidc-ebid.org\/fr\/le-conseil-dadministration-de-la-bidc-approuve-un-investissement-de-174-millions-deuros-et-de-125-millions-de-dollars-us-pour-stimuler-le-commerce-renforcer-les-infrastructures-et-soutenir-le-dev\/","title":{"rendered":"Le Conseil d&rsquo;Administration de la BIDC approuve un investissement de 174 millions d&rsquo;euros et de 125 millions de dollars US pour stimuler le commerce, renforcer les infrastructures et soutenir le developpement social en Afrique de l\u2019Ouest"},"content":{"rendered":"<p>Le Conseil d&rsquo;Administration de la Banque d&rsquo;Investissement et de D\u00e9veloppement de la CEDEAO (BIDC) a tenu sa 92<sup>\u00e8me<\/sup> session ordinaire le 30 juin 2025. Le Conseil a approuv\u00e9 un montant total de 174 millions d&rsquo;euros et 125 millions de dollars US pour financer des projets visant \u00e0 stimuler la croissance \u00e9conomique et \u00e0 favoriser l&rsquo;industrialisation de la sous-r\u00e9gion.<\/p>\n<p>Les montants approuv\u00e9s serviront \u00e0 financer les projets suivants :<\/p>\n<ul>\n<li>Un projet de 50 millions d&rsquo;euros pour la construction et l&rsquo;\u00e9quipement de six (6) centres d&rsquo;enseignement technique et de formation professionnelle (ETFP) par Planet One, en R\u00e9publique togolaise. Ce projet vise \u00e0 doter la jeunesse togolaise de comp\u00e9tences tr\u00e8s recherch\u00e9es dans divers secteurs d&rsquo;activit\u00e9. On s&rsquo;attend \u00e0 ce que 3 480 apprenants par an b\u00e9n\u00e9ficient d&rsquo;une formation\u00a0; ce qui permettra de cr\u00e9er une main-d&rsquo;\u0153uvre plus productive et plus comp\u00e9titive.<\/li>\n<li>Un projet de 25 millions de dollars US pour l&rsquo;importation de clinker par la Soci\u00e9t\u00e9 de Ciment de C\u00f4te d&rsquo;Ivoire en R\u00e9publique de C\u00f4te d&rsquo;Ivoire. Ce projet permettra d&rsquo;accro\u00eetre la disponibilit\u00e9 des produits cimentiers en C\u00f4te d&rsquo;Ivoire gr\u00e2ce \u00e0 l&rsquo;importation de 400 000 tonnes de clinker.<\/li>\n<li>Un projet de 28,9 millions d&rsquo;euros pour la modernisation et la mise aux normes de quatre (4) lyc\u00e9es agricoles en R\u00e9publique de Guin\u00e9e. Ce projet de d\u00e9veloppement multisectoriel permettra d&rsquo;am\u00e9liorer l&#8217;employabilit\u00e9 des jeunes guin\u00e9ens et d&rsquo;apporter une solution structurelle au ch\u00f4mage des jeunes.<\/li>\n<li>Un projet de 95,163 millions d&rsquo;euros pour la construction de trois microcentrales hydro\u00e9lectriques (30 MW) avec SOGEOH \u00e0 Poukou, Bolokoun et Biwbaw en R\u00e9publique de Guin\u00e9e. Ce projet vise \u00e0 exploiter le potentiel hydraulique local dans des zones mal desservies en \u00e9lectricit\u00e9 pour produire de l&rsquo;\u00e9nergie renouvelable, am\u00e9liorant ainsi les conditions de vie et g\u00e9n\u00e9rant une activit\u00e9 \u00e9conomique au profit des populations rurales.<\/li>\n<li>Un projet d&rsquo;autoroute c\u00f4ti\u00e8re Lagos-Calabar, d&rsquo;un montant de 100 millions de dollars US, en R\u00e9publique f\u00e9d\u00e9rale du Nig\u00e9ria. Ce projet, qui s&rsquo;\u00e9tend sur 47,7 km, reliera neuf \u00c9tats du Nig\u00e9ria, am\u00e9liorera l&rsquo;acc\u00e8s aux ports maritimes et aux zones agro-industrielles isol\u00e9es, et contribuera \u00e0 l&rsquo;\u00e9mergence d&rsquo;une cha\u00eene de valeur r\u00e9gionale pour aider les communaut\u00e9s c\u00f4ti\u00e8res.<\/li>\n<\/ul>\n<p>Ces engagements nouvellement approuv\u00e9s sont align\u00e9s sur les Objectifs de D\u00e9veloppement Durable (ODD) des Nations unies, en particulier l&rsquo;ODD 4 &#8211; \u00c9ducation de qualit\u00e9, l&rsquo;ODD 7 &#8211; \u00c9nergie propre et d\u2019un Co\u00fbt abordable et l&rsquo;ODD 9 &#8211; Industrie, innovation et infrastructure, ainsi que sur le plan strat\u00e9gique de la BIDC visant \u00e0 promouvoir une croissance et un d\u00e9veloppement r\u00e9silients, inclusifs et durables dans l&rsquo;espace CEDEAO. Avec cet investissement, le total des engagements de la BIDC dans la sous-r\u00e9gion s&rsquo;\u00e9l\u00e8ve \u00e0 ce jour \u00e0 plus de 5 milliards de dollars US.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Conseil d&rsquo;Administration de la Banque d&rsquo;Investissement et de D\u00e9veloppement de la CEDEAO (BIDC) a tenu sa 92\u00e8me session ordinaire le 30 juin 2025. Le Conseil a approuv\u00e9 un montant total de 174 millions d&rsquo;euros et 125 millions de dollars US pour financer des projets visant \u00e0 stimuler la croissance \u00e9conomique et \u00e0 favoriser l&rsquo;industrialisation [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":277594,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-277593","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"jetpack_featured_media_url":"https:\/\/www.bidc-ebid.org\/fr\/wp-content\/uploads\/Meeting-92-BoD.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/posts\/277593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/comments?post=277593"}],"version-history":[{"count":1,"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/posts\/277593\/revisions"}],"predecessor-version":[{"id":277595,"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/posts\/277593\/revisions\/277595"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/media\/277594"}],"wp:attachment":[{"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/media?parent=277593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/categories?post=277593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/tags?post=277593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}