{"id":277584,"date":"2025-07-02T17:18:39","date_gmt":"2025-07-02T17:18:39","guid":{"rendered":"https:\/\/www.bidc-ebid.org\/fr\/?p=277584"},"modified":"2025-07-02T17:26:57","modified_gmt":"2025-07-02T17:26:57","slug":"president-of-ebid-urges-graduants-to-champion-problem-solving-innovation-for-africas-growth","status":"publish","type":"post","link":"https:\/\/www.bidc-ebid.org\/fr\/president-of-ebid-urges-graduants-to-champion-problem-solving-innovation-for-africas-growth\/","title":{"rendered":"Le Pr\u00e9sident de la BIDC exhorte les dipl\u00f4m\u00e9s \u00e0 s\u2019engager dans la r\u00e9solution des probl\u00e8mes par l\u2019innovation pour la croissance de l&rsquo;Afrique"},"content":{"rendered":"<p>Le Chancelier de la Nobel International Business University (NiBS), Dr George Agyekum Donkor, a exhort\u00e9 les dipl\u00f4m\u00e9s de l&rsquo;universit\u00e9 \u00e0 d\u00e9fendre l&rsquo;innovation et \u00e0 promouvoir des politiques qui non seulement r\u00e9solvent les probl\u00e8mes urgents de l&rsquo;Afrique, mais prot\u00e8gent \u00e9galement les personnes vuln\u00e9rables de la soci\u00e9t\u00e9.<\/p>\n<p>Il a encourag\u00e9 les dipl\u00f4m\u00e9s \u00e0 diriger de mani\u00e8re responsable et \u00e0 appliquer avec audace la formation \u00e0 la recherche qu&rsquo;ils ont acquise, pour \u00e9clairer les politiques publiques et commerciales dans \u00ab un monde marqu\u00e9 par la volatilit\u00e9, l&rsquo;incertitude \u00e9conomique, les changements technologiques et les r\u00e9alignements globaux \u00bb.<\/p>\n<p>Le Chancelier de la premi\u00e8re \u00e9cole doctorale d&rsquo;Afrique s&rsquo;exprimait lors de la c\u00e9r\u00e9monie inaugurale de remise des dipl\u00f4mes de l&rsquo;universit\u00e9, qui s&rsquo;est d\u00e9roul\u00e9e le samedi 28 juin 2025 \u00e0 Accra. L&rsquo;\u00e9v\u00e9nement, intitul\u00e9 \u00ab <em>Leaders de la pens\u00e9e, architectes de la croissance <\/em>\u00bb, a marqu\u00e9 une \u00e9tape importante dans le paysage de l&rsquo;enseignement sup\u00e9rieur en Afrique, puisque NiBS a dipl\u00f4m\u00e9 58 de sa cohorte pionni\u00e8re de doctorants, pr\u00eats \u00e0 conduire la transformation du continent.<\/p>\n<p>Dr George Agyekum Donkor, qui est \u00e9galement le Pr\u00e9sident de la Banque d&rsquo;Investissement et de D\u00e9veloppement de la CEDEAO (BIDC) et de son Conseil d&rsquo;Administration, a fait remarquer qu&rsquo;en tant qu&rsquo;institution engag\u00e9e dans le progr\u00e8s de l&rsquo;Afrique, la BIDC reconna\u00eet l&rsquo;importance vitale de cultiver l&rsquo;expertise locale. La remise des dipl\u00f4mes \u00e0 la premi\u00e8re cohorte de NiBS repr\u00e9sente une contribution significative au capital intellectuel du continent et \u00e0 son pipeline de leadership. Dr Donkor a d\u00e9clar\u00e9\u00a0: \u00ab\u00a0Lorsque nous investissons dans le d\u00e9veloppement du potentiel humain de l&rsquo;Afrique, nous jetons les bases les plus solides d&rsquo;une croissance durable et de l&rsquo;int\u00e9gration r\u00e9gionale\u00a0\u00bb.<\/p>\n<p>La BIDC a investi des millions de dollars US dans des projets de d\u00e9veloppement de l&rsquo;\u00e9ducation au sein des \u00c9tats Membres de la CEDEAO afin de souligner le r\u00f4le cl\u00e9 que joue l&rsquo;\u00e9ducation dans l&rsquo;avancement de la croissance \u00e9conomique dans la sous-r\u00e9gion.<\/p>\n<p>La premi\u00e8re promotion de NiBS \u00e9tait compos\u00e9e d&rsquo;universitaires de douze nations africaines, qui ont obtenu des dipl\u00f4mes en innovation commerciale, en technologie financi\u00e8re et en politique de d\u00e9veloppement.\u00a0 La c\u00e9r\u00e9monie a \u00e9galement \u00e9t\u00e9 l&rsquo;occasion de lancer le r\u00e9seau mondial des anciens \u00e9tudiants de NiBS, cr\u00e9ant ainsi une plateforme de collaboration continue entre les dipl\u00f4m\u00e9s qui sont d\u00e9sormais en mesure d&rsquo;influencer la politique, les affaires et le d\u00e9veloppement social \u00e0 travers le continent.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Chancelier de la Nobel International Business University (NiBS), Dr George Agyekum Donkor, a exhort\u00e9 les dipl\u00f4m\u00e9s de l&rsquo;universit\u00e9 \u00e0 d\u00e9fendre l&rsquo;innovation et \u00e0 promouvoir des politiques qui non seulement r\u00e9solvent les probl\u00e8mes urgents de l&rsquo;Afrique, mais prot\u00e8gent \u00e9galement les personnes vuln\u00e9rables de la soci\u00e9t\u00e9. Il a encourag\u00e9 les dipl\u00f4m\u00e9s \u00e0 diriger de mani\u00e8re responsable [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":277585,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-277584","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"jetpack_featured_media_url":"https:\/\/www.bidc-ebid.org\/fr\/wp-content\/uploads\/graduation_donkor.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/posts\/277584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/comments?post=277584"}],"version-history":[{"count":4,"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/posts\/277584\/revisions"}],"predecessor-version":[{"id":277589,"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/posts\/277584\/revisions\/277589"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/media\/277585"}],"wp:attachment":[{"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/media?parent=277584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/categories?post=277584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/tags?post=277584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}