{"id":261982,"date":"2020-08-25T07:43:52","date_gmt":"2020-08-25T07:43:52","guid":{"rendered":"http:\/\/www.bidc-ebid.org\/fr\/?p=261982"},"modified":"2020-11-04T09:55:44","modified_gmt":"2020-11-04T09:55:44","slug":"lenvoye-special-de-lonu-en-visite-a-la-bidc","status":"publish","type":"post","link":"https:\/\/www.bidc-ebid.org\/fr\/lenvoye-special-de-lonu-en-visite-a-la-bidc\/","title":{"rendered":"L\u2019envoy\u00e9 sp\u00e9cial de l\u2019ONU en visite \u00e0 la BIDC"},"content":{"rendered":"<p>Le 19 ao\u00fbt 2020, le Repr\u00e9sentant sp\u00e9cial du Secr\u00e9taire g\u00e9n\u00e9ral des Nations Unies pour l\u2019Afrique de l\u2019Ouest et le Sahel, qui est \u00e9galement le Directeur du Bureau des Nations Unies pour l\u2019Afrique de l\u2019Ouest (UNOWAS), Monsieur Ibn CHAMBAS, PhD, a \u00e9t\u00e9 re\u00e7u au si\u00e8ge de la Banque \u00e0 Lom\u00e9 par le Pr\u00e9sident de la BIDC, Monsieur Agyekum DONKOR, PhD, ainsi que par les membres cl\u00e9s de la haute direction.<\/p>\n<p>CHAMBAS a salu\u00e9 la CEDEAO pour ses nombreuses r\u00e9alisations, dont la paix et la s\u00e9curit\u00e9, au demeurant cruciales, constituent la raison d\u2019\u00eatre de la Communaut\u00e9, \u00e0 savoir promouvoir l\u2019int\u00e9gration \u00e9conomique en Afrique de l\u2019ouest, stimuler le d\u00e9veloppement du secteur priv\u00e9 en Afrique de l\u2019ouest et contribuer au d\u00e9veloppement \u00e9conomique des populations de la sous-r\u00e9gion.<\/p>\n<p><strong>La libre circulation et une bonne infrastructure routi\u00e8re, sources de richesses<\/strong><\/p>\n<p>CHAMBAS a rappel\u00e9 que la libre circulation, pr\u00e9vue par les textes fondateurs de la CEDEAO, vise \u00e0 stimuler la cr\u00e9ation de richesses, domaine dans lequel le bras financier de la Communaut\u00e9, la BIDC, a un r\u00f4le majeur \u00e0 jouer.<\/p>\n<p>Citant l\u2019exemple du d\u00e9veloppement des infrastructures, qui repr\u00e9sente l\u2019un des principaux domaines d\u2019intervention de la Banque dans tous les \u00c9tats membres, M. CHAMBAS a soulign\u00e9 que sans infrastructure routi\u00e8re, les avantages li\u00e9s \u00e0 la libre circulation se trouveraient fortement amoindris. Il a \u00e9galement \u00e9voqu\u00e9 l\u2019agriculture, qu\u2019il consid\u00e8re comme un secteur important dans notre sous-r\u00e9gion, rappelant la n\u00e9cessit\u00e9 de d\u00e9velopper ce secteur pour y inclure la cha\u00eene de valeur de la transformation alimentaire afin de cr\u00e9er des emplois et d\u2019assurer la s\u00e9curit\u00e9 alimentaire de nos populations. Il a ajout\u00e9 que la BIDC se doit de continuer \u00e0 contribuer \u00e0 la croissance des secteurs vitaux de notre \u00e9conomie.<\/p>\n<p><strong>La n\u00e9gligence engendre le terrorisme<\/strong><\/p>\n<p>Invitant \u00e0 appuyer les efforts d\u00e9ploy\u00e9s par la BIDC pour mobiliser davantage de ressources, M. CHAMBAS a r\u00e9affirm\u00e9 que la Banque m\u00e9rite d\u2019\u00eatre aid\u00e9e pour soutenir le d\u00e9veloppement \u00e9conomique, en raison de son impact sur la paix et la stabilit\u00e9 de la r\u00e9gion. \u00c9voquant l\u2019exemple du Mali et d\u2019autres r\u00e9gions touch\u00e9es par les menaces terroristes, le Directeur de l\u2019UNOWAS a expliqu\u00e9 que la n\u00e9gligence constitue un vivier pour le terrorisme dans la r\u00e9gion. Il a soulign\u00e9 que les foyers propices au terrorisme dans la r\u00e9gion sont les vastes zones pauvres de la sous-r\u00e9gion o\u00f9, gr\u00e2ce aux m\u00e9dias sociaux et autres moyens de communication modernes, les jeunes de ces r\u00e9gions pauvres et isol\u00e9es ont acc\u00e8s aux informations sur les \u00e9volutions dans le domaine sportif et autres domaines se produisant ailleurs \u00e0 travers le monde, ce qui cr\u00e9e d\u2019\u00e9normes frustrations chez eux.<\/p>\n<p>Aussi, a-t-il encourag\u00e9 la BIDC \u00e0 intensifier son action en faveur du d\u00e9veloppement des infrastructures, compte tenu de ses effets multiplicateurs sur le d\u00e9veloppement durable de la r\u00e9gion, afin de dynamiser le secteur industriel et ainsi, l\u2019essor de la r\u00e9gion.<\/p>\n<p>Le Pr\u00e9sident de la BIDC, au nom de la Banque, a adress\u00e9 ses remerciements \u00e0 M. CHAMBAS pour avoir d\u00e9gag\u00e9 du temps pour rendre une visite de courtoisie \u00e0 la Banque et partager avec elle des id\u00e9es tr\u00e8s constructives.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 19 ao\u00fbt 2020, le Repr\u00e9sentant sp\u00e9cial du Secr\u00e9taire g\u00e9n\u00e9ral des Nations Unies pour l\u2019Afrique de l\u2019Ouest et le Sahel, qui est \u00e9galement le Directeur du Bureau des Nations Unies pour l\u2019Afrique de l\u2019Ouest (UNOWAS), Monsieur Ibn CHAMBAS, PhD, a \u00e9t\u00e9 re\u00e7u au si\u00e8ge de la Banque \u00e0 Lom\u00e9 par le Pr\u00e9sident de la BIDC, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":213590,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[179,180,97],"class_list":["post-261982","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","tag-ibn-chambas","tag-onu","tag-unowas"],"jetpack_featured_media_url":"https:\/\/www.bidc-ebid.org\/fr\/wp-content\/uploads\/article_vide_fonce.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/posts\/261982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/comments?post=261982"}],"version-history":[{"count":4,"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/posts\/261982\/revisions"}],"predecessor-version":[{"id":275285,"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/posts\/261982\/revisions\/275285"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/media\/213590"}],"wp:attachment":[{"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/media?parent=261982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/categories?post=261982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/tags?post=261982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}