{"id":139903,"date":"2020-02-07T11:30:11","date_gmt":"2020-02-07T11:30:11","guid":{"rendered":"https:\/\/www.bidc-ebid.org\/fr\/?p=139903"},"modified":"2020-11-03T10:40:50","modified_gmt":"2020-11-03T10:40:50","slug":"mise-en-service-de-la-centrale-thermique-de-120-mw-cofinancee-par-la-bidc-la-boad-et-la-bid","status":"publish","type":"post","link":"https:\/\/www.bidc-ebid.org\/fr\/mise-en-service-de-la-centrale-thermique-de-120-mw-cofinancee-par-la-bidc-la-boad-et-la-bid\/","title":{"rendered":"Mise en service de la centrale thermique de 120 mw cofinanc\u00e9e par la BIDC, la BOAD et la BID"},"content":{"rendered":"<p>La centrale thermique Maria \u2013 Gleta 2 de 120 MW en R\u00e9publique du B\u00e9nin, financ\u00e9e par un consortium comprenant la Banque d\u2019investissement et de d\u00e9veloppement de la CEDEAO (BIDC), la Banque Islamique de d\u00e9veloppement (BID) et la Banque Ouest Africaine de D\u00e9veloppement (BOAD), en collaboration avec la R\u00e9publique du B\u00e9nin, a \u00e9t\u00e9 mise en service le 29 ao\u00fbt 2019.<\/p>\n<p>Ce projet, qui s\u2019inscrit dans la ligne de l\u2019action de la BIDC visant \u00e0 soutenir le d\u00e9veloppement des secteurs cl\u00e9s de l\u2019\u00e9conomie des Etats membres de la CEDEAO, a co\u00fbt\u00e9 cent six milliards neuf cent soixante-douze millions de francs (106,972 milliards de FCFA). Plus pr\u00e9cis\u00e9ment, le projet devrait r\u00e9duire le d\u00e9ficit \u00e9nerg\u00e9tique du pays, diversifier ses sources d\u2019approvisionnement en \u00e9lectricit\u00e9, am\u00e9liorer l\u2019infrastructure \u00e9nerg\u00e9tique, r\u00e9duire le co\u00fbt des services, cr\u00e9er un environnement favorable \u00e0 la croissance \u00e9conomique et conduire \u00e0 terme \u00e0 une \u00e9nergie suffisante d\u2019ici 2021.<\/p>\n<p>Dans son allocution lors de la c\u00e9r\u00e9monie de mise en service, le Pr\u00e9sident de la BIDC, M. Bashir IFO, repr\u00e9sent\u00e9 par le Vice-Pr\u00e9sident charg\u00e9 des op\u00e9rations, M. Abdoulaye FALL, a soulign\u00e9 que la R\u00e9publique du B\u00e9nin a b\u00e9n\u00e9fici\u00e9 de l\u2019\u00e9ventail complet des opportunit\u00e9s de financement diversifi\u00e9es offertes par les guichets des secteurs public et priv\u00e9 de la BIDC.\u00a0 Il a ajout\u00e9 qu\u2019au 31 d\u00e9cembre 2018, le montant total des engagements de la Banque au B\u00e9nin s\u2019\u00e9levait \u00e0 cent cinq milliards de francs (105 milliards de FCFA), dont quatre-vingt-dix-sept milliards de francs (97 milliards de FCFA) \u00e9taient investis dans le secteur public, et huit milliards de francs (8 milliards de FCFA) dans le secteur priv\u00e9. La coop\u00e9ration de la BIDC avec la R\u00e9publique du B\u00e9nin indique que la Banque a investi 34% des ressources dans le secteur de l\u2019\u00e9nergie et 62% dans les secteurs des transports et des t\u00e9l\u00e9communications.<\/p>\n<p>Outre la centrale thermique Maria Gleta 2 de 120 MW, la BIDC est intervenue dans des projets d\u2019\u00e9lectrification rurale tels que l\u2019\u00e9lectrification de cinquante-huit (58) et soixante-sept (67) communaut\u00e9s, pour un montant de vingt et un milliards de francs (21 milliards de FCFA).\u00a0 La troisi\u00e8me d\u2019une s\u00e9rie d\u2019interventions similaires est l\u2019\u00e9lectrification de cent (100) communaut\u00e9s par r\u00e9seau centralis\u00e9, pour un montant de dix-sept milliards de francs (17 milliards de FCFA).\u00a0 Enfin, le guichet du secteur priv\u00e9 de la BIDC appuiera la Soci\u00e9t\u00e9 B\u00e9ninoise d\u2019Energie Electrique (SBEE) dans le cadre d\u2019un projet relatif \u00e0 l\u2019acquisition de compteurs \u00e9lectriques pr\u00e9pay\u00e9s.<\/p>\n<p>Le Vice-pr\u00e9sident, Op\u00e9rations de la BIDC a conclu en rappelant que l\u2019objectif principal de la Banque est de contribuer au d\u00e9veloppement \u00e9conomique de l\u2019Afrique de l\u2019Ouest par le financement de projets des secteurs public et priv\u00e9 dans les domaines suivants : transports, \u00e9nergie, t\u00e9l\u00e9communications, services, r\u00e9duction de la pauvret\u00e9, environnement entre autres.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La centrale thermique Maria \u2013 Gleta 2 de 120 MW en R\u00e9publique du B\u00e9nin, financ\u00e9e par un consortium comprenant la Banque d\u2019investissement et de d\u00e9veloppement de la CEDEAO (BIDC), la Banque Islamique de d\u00e9veloppement (BID) et la Banque Ouest Africaine de D\u00e9veloppement (BOAD), en collaboration avec la R\u00e9publique du B\u00e9nin, a \u00e9t\u00e9 mise en service [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":140064,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[148,43,151,38,152,42,45],"class_list":["post-139903","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","tag-bidc","tag-boad","tag-centrale-thermique","tag-ebid","tag-energie","tag-idb","tag-sbee"],"jetpack_featured_media_url":"https:\/\/www.bidc-ebid.org\/fr\/wp-content\/uploads\/maria_gleta.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/posts\/139903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/comments?post=139903"}],"version-history":[{"count":4,"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/posts\/139903\/revisions"}],"predecessor-version":[{"id":275305,"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/posts\/139903\/revisions\/275305"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/media\/140064"}],"wp:attachment":[{"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/media?parent=139903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/categories?post=139903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bidc-ebid.org\/fr\/wp-json\/wp\/v2\/tags?post=139903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}